{"id":395,"date":"2026-07-15T09:53:25","date_gmt":"2026-07-15T09:53:25","guid":{"rendered":"https:\/\/www.gillescolle.be\/?post_type=portfolio&#038;p=395"},"modified":"2026-07-15T09:53:26","modified_gmt":"2026-07-15T09:53:26","slug":"goodies","status":"publish","type":"portfolio","link":"https:\/\/www.gillescolle.be\/index.php\/portfolio\/goodies\/","title":{"rendered":"GOODIES"},"content":{"rendered":"","protected":false},"featured_media":370,"menu_order":0,"template":"","portfolio_categories":[42],"class_list":["post-395","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/portfolio\/395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":1,"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/portfolio\/395\/revisions"}],"predecessor-version":[{"id":396,"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/portfolio\/395\/revisions\/396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/media\/370"}],"wp:attachment":[{"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/media?parent=395"}],"wp:term":[{"taxonomy":"portfolio_categories","embeddable":true,"href":"https:\/\/www.gillescolle.be\/index.php\/wp-json\/wp\/v2\/portfolio_categories?post=395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}